{"id":107685,"date":"2024-05-21T20:32:19","date_gmt":"2024-05-24T13:44:06","guid":{"rendered":"https:\/\/depagterinterieurs.nl\/?post_type=product&#038;p=107685"},"modified":"2024-05-24T14:44:07","modified_gmt":"2024-05-24T13:44:07","slug":"nachttisch-granada-schwarz-kopie","status":"publish","type":"product","link":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-granada-schwarz-kopie\/","title":{"rendered":"Nachttisch Granada Schwarz"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Schwarz geschliffener Nachttisch &#8216;Granada&#8217; mit 4 Schubladen, aus altem Kiefernholz.<\/p>\n<p>Auch in schlichtem altem Kiefernholz erh\u00e4ltlich.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":76145,"template":"","meta":[],"product_brand":[],"product_cat":[409,93,96,399,383],"product_tag":[],"class_list":["post-107685","product","type-product","status-publish","has-post-thumbnail","product_cat-de-pagter-interieurs","product_cat-elmwood-old-pine-de","product_cat-kleine-mobel","product_cat-marke","product_cat-nachttische","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nachttisch Granada Schwarz - De Pagter Interieurs<\/title>\n<meta name=\"description\" content=\"Schwarz geschliffener Nachttisch &#039;Granada&#039; mit 4 Schubladen, aus altem Kiefernholz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-granada-schwarz-kopie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachttisch Granada Schwarz - De Pagter Interieurs\" \/>\n<meta property=\"og:description\" content=\"Schwarz geschliffener Nachttisch &#039;Granada&#039; mit 4 Schubladen, aus altem Kiefernholz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-granada-schwarz-kopie\/\" \/>\n<meta property=\"og:site_name\" content=\"De Pagter Interieurs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/depagterinterieurs\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-24T13:44:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2023\/03\/IMG_6379.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-granada-schwarz-kopie\\\/\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-granada-schwarz-kopie\\\/\",\"name\":\"Nachttisch Granada Schwarz - De Pagter Interieurs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-granada-schwarz-kopie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-granada-schwarz-kopie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/IMG_6379.jpeg\",\"datePublished\":\"2024-05-24T13:44:06+00:00\",\"dateModified\":\"2024-05-24T13:44:07+00:00\",\"description\":\"Schwarz geschliffener Nachttisch 'Granada' mit 4 Schubladen, aus altem Kiefernholz.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-granada-schwarz-kopie\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-granada-schwarz-kopie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-granada-schwarz-kopie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/IMG_6379.jpeg\",\"contentUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/IMG_6379.jpeg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-granada-schwarz-kopie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/homepagina-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kollektion\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/kollektion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nachttisch Granada Schwarz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/\",\"name\":\"De Pagter Interieurs\",\"description\":\"M\u00f6belgesch\u00e4fte in Middelburg - Domburg - Veere\",\"publisher\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#organization\",\"name\":\"De Pagter Interieurs\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo.svg\",\"width\":157,\"height\":53,\"caption\":\"De Pagter Interieurs\"},\"image\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/depagterinterieurs\\\/\",\"https:\\\/\\\/www.instagram.com\\\/depagterinterieurs\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nachttisch Granada Schwarz - De Pagter Interieurs","description":"Schwarz geschliffener Nachttisch 'Granada' mit 4 Schubladen, aus altem Kiefernholz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-granada-schwarz-kopie\/","og_locale":"de_DE","og_type":"article","og_title":"Nachttisch Granada Schwarz - De Pagter Interieurs","og_description":"Schwarz geschliffener Nachttisch 'Granada' mit 4 Schubladen, aus altem Kiefernholz.","og_url":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-granada-schwarz-kopie\/","og_site_name":"De Pagter Interieurs","article_publisher":"https:\/\/www.facebook.com\/depagterinterieurs\/","article_modified_time":"2024-05-24T13:44:07+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2023\/03\/IMG_6379.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-granada-schwarz-kopie\/","url":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-granada-schwarz-kopie\/","name":"Nachttisch Granada Schwarz - De Pagter Interieurs","isPartOf":{"@id":"https:\/\/depagterinterieurs.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-granada-schwarz-kopie\/#primaryimage"},"image":{"@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-granada-schwarz-kopie\/#primaryimage"},"thumbnailUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2023\/03\/IMG_6379.jpeg","datePublished":"2024-05-24T13:44:06+00:00","dateModified":"2024-05-24T13:44:07+00:00","description":"Schwarz geschliffener Nachttisch 'Granada' mit 4 Schubladen, aus altem Kiefernholz.","breadcrumb":{"@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-granada-schwarz-kopie\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-granada-schwarz-kopie\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-granada-schwarz-kopie\/#primaryimage","url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2023\/03\/IMG_6379.jpeg","contentUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2023\/03\/IMG_6379.jpeg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-granada-schwarz-kopie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/depagterinterieurs.nl\/de\/homepagina-de\/"},{"@type":"ListItem","position":2,"name":"Kollektion","item":"https:\/\/depagterinterieurs.nl\/de\/kollektion\/"},{"@type":"ListItem","position":3,"name":"Nachttisch Granada Schwarz"}]},{"@type":"WebSite","@id":"https:\/\/depagterinterieurs.nl\/de\/#website","url":"https:\/\/depagterinterieurs.nl\/de\/","name":"De Pagter Interieurs","description":"M\u00f6belgesch\u00e4fte in Middelburg - Domburg - Veere","publisher":{"@id":"https:\/\/depagterinterieurs.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/depagterinterieurs.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/depagterinterieurs.nl\/de\/#organization","name":"De Pagter Interieurs","url":"https:\/\/depagterinterieurs.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/depagterinterieurs.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/02\/logo.svg","contentUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/02\/logo.svg","width":157,"height":53,"caption":"De Pagter Interieurs"},"image":{"@id":"https:\/\/depagterinterieurs.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/depagterinterieurs\/","https:\/\/www.instagram.com\/depagterinterieurs\/"]}]}},"_links":{"self":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product\/107685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/media\/76145"}],"wp:attachment":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/media?parent=107685"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product_brand?post=107685"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product_cat?post=107685"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product_tag?post=107685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}