{"id":147039,"date":"2025-03-11T21:11:45","date_gmt":"2025-03-11T20:17:56","guid":{"rendered":"https:\/\/depagterinterieurs.nl\/?post_type=product&#038;p=147039"},"modified":"2025-03-11T21:21:51","modified_gmt":"2025-03-11T20:21:51","slug":"nachttisch-almeria-kopie","status":"publish","type":"product","link":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-almeria-kopie\/","title":{"rendered":"Nachttisch Almeria"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>L\u00e4ndlicher Nachttisch &#8216;Almeria&#8217; mit 2 T\u00fcren und 2 Schubladen, aus altem Kiefernholz.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":81814,"template":"","meta":[],"product_brand":[],"product_cat":[409,93,96,399,383],"product_tag":[],"class_list":{"0":"post-147039","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-de-pagter-interieurs","7":"product_cat-elmwood-old-pine-de","8":"product_cat-kleine-mobel","9":"product_cat-marke","10":"product_cat-nachttische","12":"first","13":"instock","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nachttisch Almeria - De Pagter Interieurs<\/title>\n<meta name=\"description\" content=\"L\u00e4ndlicher Nachttisch &#039;Almeria&#039; mit 2 T\u00fcren und 2 Schubladen, aus altem Kiefernholz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-almeria-kopie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachttisch Almeria - De Pagter Interieurs\" \/>\n<meta property=\"og:description\" content=\"L\u00e4ndlicher Nachttisch &#039;Almeria&#039; mit 2 T\u00fcren und 2 Schubladen, aus altem Kiefernholz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-almeria-kopie\/\" \/>\n<meta property=\"og:site_name\" content=\"De Pagter Interieurs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/depagterinterieurs\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-11T20:21:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2023\/07\/IMG_8433.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-almeria-kopie\\\/\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-almeria-kopie\\\/\",\"name\":\"Nachttisch Almeria - De Pagter Interieurs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-almeria-kopie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-almeria-kopie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/IMG_8433.jpeg\",\"datePublished\":\"2025-03-11T20:17:56+00:00\",\"dateModified\":\"2025-03-11T20:21:51+00:00\",\"description\":\"L\u00e4ndlicher Nachttisch 'Almeria' mit 2 T\u00fcren und 2 Schubladen, aus altem Kiefernholz.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-almeria-kopie\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-almeria-kopie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-almeria-kopie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/IMG_8433.jpeg\",\"contentUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/IMG_8433.jpeg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/nachttisch-almeria-kopie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/homepagina-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kollektion\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/kollektion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nachttisch Almeria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/\",\"name\":\"De Pagter Interieurs\",\"description\":\"M\u00f6belgesch\u00e4fte in Middelburg - Domburg - Veere\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nachttisch Almeria - De Pagter Interieurs","description":"L\u00e4ndlicher Nachttisch 'Almeria' mit 2 T\u00fcren und 2 Schubladen, aus altem Kiefernholz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-almeria-kopie\/","og_locale":"de_DE","og_type":"article","og_title":"Nachttisch Almeria - De Pagter Interieurs","og_description":"L\u00e4ndlicher Nachttisch 'Almeria' mit 2 T\u00fcren und 2 Schubladen, aus altem Kiefernholz.","og_url":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-almeria-kopie\/","og_site_name":"De Pagter Interieurs","article_publisher":"https:\/\/www.facebook.com\/depagterinterieurs\/","article_modified_time":"2025-03-11T20:21:51+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2023\/07\/IMG_8433.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-almeria-kopie\/","url":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-almeria-kopie\/","name":"Nachttisch Almeria - De Pagter Interieurs","isPartOf":{"@id":"https:\/\/depagterinterieurs.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-almeria-kopie\/#primaryimage"},"image":{"@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-almeria-kopie\/#primaryimage"},"thumbnailUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2023\/07\/IMG_8433.jpeg","datePublished":"2025-03-11T20:17:56+00:00","dateModified":"2025-03-11T20:21:51+00:00","description":"L\u00e4ndlicher Nachttisch 'Almeria' mit 2 T\u00fcren und 2 Schubladen, aus altem Kiefernholz.","breadcrumb":{"@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-almeria-kopie\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-almeria-kopie\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-almeria-kopie\/#primaryimage","url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2023\/07\/IMG_8433.jpeg","contentUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2023\/07\/IMG_8433.jpeg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/nachttisch-almeria-kopie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/depagterinterieurs.nl\/de\/homepagina-de\/"},{"@type":"ListItem","position":2,"name":"Kollektion","item":"https:\/\/depagterinterieurs.nl\/de\/kollektion\/"},{"@type":"ListItem","position":3,"name":"Nachttisch Almeria"}]},{"@type":"WebSite","@id":"https:\/\/depagterinterieurs.nl\/de\/#website","url":"https:\/\/depagterinterieurs.nl\/de\/","name":"De Pagter Interieurs","description":"M\u00f6belgesch\u00e4fte in Middelburg - Domburg - Veere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/depagterinterieurs.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product\/147039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/media\/81814"}],"wp:attachment":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/media?parent=147039"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product_brand?post=147039"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product_cat?post=147039"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product_tag?post=147039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}