{"id":177327,"date":"2025-12-12T16:45:28","date_gmt":"2025-12-12T15:45:28","guid":{"rendered":"https:\/\/depagterinterieurs.nl\/collectie\/uncategorized\/alter-kiefern-couchtisch-103x59cm\/"},"modified":"2025-12-12T16:55:52","modified_gmt":"2025-12-12T15:55:52","slug":"alter-kiefern-couchtisch-103x59cm","status":"publish","type":"product","link":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/alter-kiefern-couchtisch-103x59cm\/","title":{"rendered":"Alter Kiefern Couchtisch 103X59CM"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Couchtisch aus altem Kiefernholz.<\/p>\n","protected":false},"featured_media":177295,"template":"","meta":[],"product_brand":[],"product_cat":[342,409,93,399,101],"product_tag":[],"class_list":["post-177327","product","type-product","status-publish","has-post-thumbnail","product_cat-couchtische","product_cat-de-pagter-interieurs","product_cat-elmwood-old-pine-de","product_cat-marke","product_cat-wand-und-couchtische","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alter Kiefern Couchtisch 103X59CM - De Pagter Interieurs<\/title>\n<meta name=\"description\" content=\"Couchtisch aus altem Kiefernholz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/alter-kiefern-couchtisch-103x59cm\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alter Kiefern Couchtisch 103X59CM - De Pagter Interieurs\" \/>\n<meta property=\"og:description\" content=\"Couchtisch aus altem Kiefernholz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/alter-kiefern-couchtisch-103x59cm\/\" \/>\n<meta property=\"og:site_name\" content=\"De Pagter Interieurs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/depagterinterieurs\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-12T15:55:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2025\/12\/IMG_1975.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/alter-kiefern-couchtisch-103x59cm\\\/\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/alter-kiefern-couchtisch-103x59cm\\\/\",\"name\":\"Alter Kiefern Couchtisch 103X59CM - De Pagter Interieurs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/alter-kiefern-couchtisch-103x59cm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/alter-kiefern-couchtisch-103x59cm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/IMG_1975.jpg\",\"datePublished\":\"2025-12-12T15:45:28+00:00\",\"dateModified\":\"2025-12-12T15:55:52+00:00\",\"description\":\"Couchtisch aus altem Kiefernholz.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/alter-kiefern-couchtisch-103x59cm\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/alter-kiefern-couchtisch-103x59cm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/alter-kiefern-couchtisch-103x59cm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/IMG_1975.jpg\",\"contentUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/IMG_1975.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/alter-kiefern-couchtisch-103x59cm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/homepagina-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kollektion\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/kollektion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alter Kiefern Couchtisch 103X59CM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/\",\"name\":\"De Pagter Interieurs\",\"description\":\"M\u00f6belgesch\u00e4fte in Middelburg - Domburg - Veere\",\"publisher\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#organization\",\"name\":\"De Pagter Interieurs\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo.svg\",\"width\":157,\"height\":53,\"caption\":\"De Pagter Interieurs\"},\"image\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/depagterinterieurs\\\/\",\"https:\\\/\\\/www.instagram.com\\\/depagterinterieurs\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alter Kiefern Couchtisch 103X59CM - De Pagter Interieurs","description":"Couchtisch aus altem Kiefernholz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/alter-kiefern-couchtisch-103x59cm\/","og_locale":"de_DE","og_type":"article","og_title":"Alter Kiefern Couchtisch 103X59CM - De Pagter Interieurs","og_description":"Couchtisch aus altem Kiefernholz.","og_url":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/alter-kiefern-couchtisch-103x59cm\/","og_site_name":"De Pagter Interieurs","article_publisher":"https:\/\/www.facebook.com\/depagterinterieurs\/","article_modified_time":"2025-12-12T15:55:52+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2025\/12\/IMG_1975.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/alter-kiefern-couchtisch-103x59cm\/","url":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/alter-kiefern-couchtisch-103x59cm\/","name":"Alter Kiefern Couchtisch 103X59CM - De Pagter Interieurs","isPartOf":{"@id":"https:\/\/depagterinterieurs.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/alter-kiefern-couchtisch-103x59cm\/#primaryimage"},"image":{"@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/alter-kiefern-couchtisch-103x59cm\/#primaryimage"},"thumbnailUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2025\/12\/IMG_1975.jpg","datePublished":"2025-12-12T15:45:28+00:00","dateModified":"2025-12-12T15:55:52+00:00","description":"Couchtisch aus altem Kiefernholz.","breadcrumb":{"@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/alter-kiefern-couchtisch-103x59cm\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/alter-kiefern-couchtisch-103x59cm\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/alter-kiefern-couchtisch-103x59cm\/#primaryimage","url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2025\/12\/IMG_1975.jpg","contentUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2025\/12\/IMG_1975.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/alter-kiefern-couchtisch-103x59cm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/depagterinterieurs.nl\/de\/homepagina-de\/"},{"@type":"ListItem","position":2,"name":"Kollektion","item":"https:\/\/depagterinterieurs.nl\/de\/kollektion\/"},{"@type":"ListItem","position":3,"name":"Alter Kiefern Couchtisch 103X59CM"}]},{"@type":"WebSite","@id":"https:\/\/depagterinterieurs.nl\/de\/#website","url":"https:\/\/depagterinterieurs.nl\/de\/","name":"De Pagter Interieurs","description":"M\u00f6belgesch\u00e4fte in Middelburg - Domburg - Veere","publisher":{"@id":"https:\/\/depagterinterieurs.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/depagterinterieurs.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/depagterinterieurs.nl\/de\/#organization","name":"De Pagter Interieurs","url":"https:\/\/depagterinterieurs.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/depagterinterieurs.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/02\/logo.svg","contentUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/02\/logo.svg","width":157,"height":53,"caption":"De Pagter Interieurs"},"image":{"@id":"https:\/\/depagterinterieurs.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/depagterinterieurs\/","https:\/\/www.instagram.com\/depagterinterieurs\/"]}]}},"_links":{"self":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product\/177327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/media\/177295"}],"wp:attachment":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/media?parent=177327"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product_brand?post=177327"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product_cat?post=177327"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product_tag?post=177327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}