{"id":200283,"date":"2026-05-11T15:33:44","date_gmt":"2026-05-11T14:33:44","guid":{"rendered":"https:\/\/depagterinterieurs.nl\/collectie\/uncategorized\/antikes-chinesisches-sideboard-232cm\/"},"modified":"2026-05-12T10:52:49","modified_gmt":"2026-05-12T09:52:49","slug":"antikes-chinesisches-sideboard-232cm","status":"publish","type":"product","link":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/antikes-chinesisches-sideboard-232cm\/","title":{"rendered":"Antikes Chinesisches Sideboard 232CM"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Antikes chinesisches Sideboard mit drei T\u00fcren und Schnitzerei, gefertigt aus altem Kiefernholz.<\/p>\n","protected":false},"featured_media":199738,"template":"","meta":[],"product_brand":[],"product_cat":[409,93,399,95,354],"product_tag":[],"class_list":{"0":"post-200283","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-de-pagter-interieurs","7":"product_cat-elmwood-old-pine-de","8":"product_cat-marke","9":"product_cat-schranke-sideboards","10":"product_cat-sideboards-de","12":"first","13":"instock","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Antikes Chinesisches Sideboard 232CM - De Pagter Interieurs<\/title>\n<meta name=\"description\" content=\"Antikes chinesisches Sideboard mit drei T\u00fcren und Schnitzerei, gefertigt aus altem Kiefernholz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/antikes-chinesisches-sideboard-232cm\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antikes Chinesisches Sideboard 232CM - De Pagter Interieurs\" \/>\n<meta property=\"og:description\" content=\"Antikes chinesisches Sideboard mit drei T\u00fcren und Schnitzerei, gefertigt aus altem Kiefernholz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/antikes-chinesisches-sideboard-232cm\/\" \/>\n<meta property=\"og:site_name\" content=\"De Pagter Interieurs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/depagterinterieurs\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T09:52:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/05\/IMG_6095.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/antikes-chinesisches-sideboard-232cm\\\/\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/antikes-chinesisches-sideboard-232cm\\\/\",\"name\":\"Antikes Chinesisches Sideboard 232CM - De Pagter Interieurs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/antikes-chinesisches-sideboard-232cm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/antikes-chinesisches-sideboard-232cm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_6095.jpg\",\"datePublished\":\"2026-05-11T14:33:44+00:00\",\"dateModified\":\"2026-05-12T09:52:49+00:00\",\"description\":\"Antikes chinesisches Sideboard mit drei T\u00fcren und Schnitzerei, gefertigt aus altem Kiefernholz.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/antikes-chinesisches-sideboard-232cm\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/antikes-chinesisches-sideboard-232cm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/antikes-chinesisches-sideboard-232cm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_6095.jpg\",\"contentUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_6095.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/collectie\\\/marke\\\/de-pagter-interieurs\\\/antikes-chinesisches-sideboard-232cm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/homepagina-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kollektion\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/kollektion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Antikes Chinesisches Sideboard 232CM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/\",\"name\":\"De Pagter Interieurs\",\"description\":\"M\u00f6belgesch\u00e4fte in Middelburg - Domburg - Veere\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/depagterinterieurs.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antikes Chinesisches Sideboard 232CM - De Pagter Interieurs","description":"Antikes chinesisches Sideboard mit drei T\u00fcren und Schnitzerei, gefertigt aus altem Kiefernholz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/antikes-chinesisches-sideboard-232cm\/","og_locale":"de_DE","og_type":"article","og_title":"Antikes Chinesisches Sideboard 232CM - De Pagter Interieurs","og_description":"Antikes chinesisches Sideboard mit drei T\u00fcren und Schnitzerei, gefertigt aus altem Kiefernholz.","og_url":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/antikes-chinesisches-sideboard-232cm\/","og_site_name":"De Pagter Interieurs","article_publisher":"https:\/\/www.facebook.com\/depagterinterieurs\/","article_modified_time":"2026-05-12T09:52:49+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/05\/IMG_6095.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/antikes-chinesisches-sideboard-232cm\/","url":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/antikes-chinesisches-sideboard-232cm\/","name":"Antikes Chinesisches Sideboard 232CM - De Pagter Interieurs","isPartOf":{"@id":"https:\/\/depagterinterieurs.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/antikes-chinesisches-sideboard-232cm\/#primaryimage"},"image":{"@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/antikes-chinesisches-sideboard-232cm\/#primaryimage"},"thumbnailUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/05\/IMG_6095.jpg","datePublished":"2026-05-11T14:33:44+00:00","dateModified":"2026-05-12T09:52:49+00:00","description":"Antikes chinesisches Sideboard mit drei T\u00fcren und Schnitzerei, gefertigt aus altem Kiefernholz.","breadcrumb":{"@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/antikes-chinesisches-sideboard-232cm\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/antikes-chinesisches-sideboard-232cm\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/antikes-chinesisches-sideboard-232cm\/#primaryimage","url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/05\/IMG_6095.jpg","contentUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/05\/IMG_6095.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/depagterinterieurs.nl\/de\/collectie\/marke\/de-pagter-interieurs\/antikes-chinesisches-sideboard-232cm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/depagterinterieurs.nl\/de\/homepagina-de\/"},{"@type":"ListItem","position":2,"name":"Kollektion","item":"https:\/\/depagterinterieurs.nl\/de\/kollektion\/"},{"@type":"ListItem","position":3,"name":"Antikes Chinesisches Sideboard 232CM"}]},{"@type":"WebSite","@id":"https:\/\/depagterinterieurs.nl\/de\/#website","url":"https:\/\/depagterinterieurs.nl\/de\/","name":"De Pagter Interieurs","description":"M\u00f6belgesch\u00e4fte in Middelburg - Domburg - Veere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/depagterinterieurs.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product\/200283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/media\/199738"}],"wp:attachment":[{"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/media?parent=200283"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product_brand?post=200283"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product_cat?post=200283"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/de\/wp-json\/wp\/v2\/product_tag?post=200283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}