{"id":186375,"date":"2026-02-25T16:15:07","date_gmt":"2026-02-25T15:15:07","guid":{"rendered":"https:\/\/depagterinterieurs.nl\/collectie\/uncategorized\/chair-leroy\/"},"modified":"2026-02-25T16:21:42","modified_gmt":"2026-02-25T15:21:42","slug":"chair-leroy","status":"publish","type":"product","link":"https:\/\/depagterinterieurs.nl\/en\/collectie\/chairs\/chair-leroy\/","title":{"rendered":"Chair Leroy"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Dining chair Leroy, with armrest, with skate wheel, made of leather: Africa &#8211; Testa di Moro.<\/p>\n<p>View all the options for the chair <strong><a href=\"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2025\/03\/LENNY-LEROY-NL-01-01-2025_NL.pdf\">here<\/a><\/strong> .<\/p>\n","protected":false},"featured_media":63379,"template":"","meta":[],"product_brand":[],"product_cat":[85],"product_tag":[],"class_list":{"0":"post-186375","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chairs","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chair Leroy - De Pagter Interieurs<\/title>\n<meta name=\"description\" content=\"Dining chair Leroy, with armrest, with skate wheel, made of leather: Africa - Testa di Moro. View all options for the chair here.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/depagterinterieurs.nl\/en\/collectie\/chairs\/chair-leroy\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chair Leroy - De Pagter Interieurs\" \/>\n<meta property=\"og:description\" content=\"Dining chair Leroy, with armrest, with skate wheel, made of leather: Africa - Testa di Moro. View all options for the chair here.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/depagterinterieurs.nl\/en\/collectie\/chairs\/chair-leroy\/\" \/>\n<meta property=\"og:site_name\" content=\"De Pagter Interieurs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/depagterinterieurs\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T15:21:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2022\/04\/IMG_1064.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/en\\\/collectie\\\/chairs\\\/chair-leroy\\\/\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/en\\\/collectie\\\/chairs\\\/chair-leroy\\\/\",\"name\":\"Chair Leroy - De Pagter Interieurs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/en\\\/collectie\\\/chairs\\\/chair-leroy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/en\\\/collectie\\\/chairs\\\/chair-leroy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/IMG_1064.jpg\",\"datePublished\":\"2026-02-25T15:15:07+00:00\",\"dateModified\":\"2026-02-25T15:21:42+00:00\",\"description\":\"Dining chair Leroy, with armrest, with skate wheel, made of leather: Africa - Testa di Moro. View all options for the chair here.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/en\\\/collectie\\\/chairs\\\/chair-leroy\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/depagterinterieurs.nl\\\/en\\\/collectie\\\/chairs\\\/chair-leroy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/en\\\/collectie\\\/chairs\\\/chair-leroy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/IMG_1064.jpg\",\"contentUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/IMG_1064.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/en\\\/collectie\\\/chairs\\\/chair-leroy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/en\\\/homepagina-en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collection\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/en\\\/collection\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chair Leroy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/en\\\/\",\"name\":\"De Pagter Interieurs\",\"description\":\"Furniture stores in Middelburg - Domburg - Veere\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/depagterinterieurs.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chair Leroy - De Pagter Interieurs","description":"Dining chair Leroy, with armrest, with skate wheel, made of leather: Africa - Testa di Moro. View all options for the chair here.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/depagterinterieurs.nl\/en\/collectie\/chairs\/chair-leroy\/","og_locale":"en_US","og_type":"article","og_title":"Chair Leroy - De Pagter Interieurs","og_description":"Dining chair Leroy, with armrest, with skate wheel, made of leather: Africa - Testa di Moro. View all options for the chair here.","og_url":"https:\/\/depagterinterieurs.nl\/en\/collectie\/chairs\/chair-leroy\/","og_site_name":"De Pagter Interieurs","article_publisher":"https:\/\/www.facebook.com\/depagterinterieurs\/","article_modified_time":"2026-02-25T15:21:42+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2022\/04\/IMG_1064.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/depagterinterieurs.nl\/en\/collectie\/chairs\/chair-leroy\/","url":"https:\/\/depagterinterieurs.nl\/en\/collectie\/chairs\/chair-leroy\/","name":"Chair Leroy - De Pagter Interieurs","isPartOf":{"@id":"https:\/\/depagterinterieurs.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/depagterinterieurs.nl\/en\/collectie\/chairs\/chair-leroy\/#primaryimage"},"image":{"@id":"https:\/\/depagterinterieurs.nl\/en\/collectie\/chairs\/chair-leroy\/#primaryimage"},"thumbnailUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2022\/04\/IMG_1064.jpg","datePublished":"2026-02-25T15:15:07+00:00","dateModified":"2026-02-25T15:21:42+00:00","description":"Dining chair Leroy, with armrest, with skate wheel, made of leather: Africa - Testa di Moro. View all options for the chair here.","breadcrumb":{"@id":"https:\/\/depagterinterieurs.nl\/en\/collectie\/chairs\/chair-leroy\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/depagterinterieurs.nl\/en\/collectie\/chairs\/chair-leroy\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/depagterinterieurs.nl\/en\/collectie\/chairs\/chair-leroy\/#primaryimage","url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2022\/04\/IMG_1064.jpg","contentUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2022\/04\/IMG_1064.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/depagterinterieurs.nl\/en\/collectie\/chairs\/chair-leroy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/depagterinterieurs.nl\/en\/homepagina-en\/"},{"@type":"ListItem","position":2,"name":"Collection","item":"https:\/\/depagterinterieurs.nl\/en\/collection\/"},{"@type":"ListItem","position":3,"name":"Chair Leroy"}]},{"@type":"WebSite","@id":"https:\/\/depagterinterieurs.nl\/en\/#website","url":"https:\/\/depagterinterieurs.nl\/en\/","name":"De Pagter Interieurs","description":"Furniture stores in Middelburg - Domburg - Veere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/depagterinterieurs.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/depagterinterieurs.nl\/en\/wp-json\/wp\/v2\/product\/186375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/depagterinterieurs.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/depagterinterieurs.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/en\/wp-json\/wp\/v2\/media\/63379"}],"wp:attachment":[{"href":"https:\/\/depagterinterieurs.nl\/en\/wp-json\/wp\/v2\/media?parent=186375"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/en\/wp-json\/wp\/v2\/product_brand?post=186375"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/en\/wp-json\/wp\/v2\/product_cat?post=186375"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/en\/wp-json\/wp\/v2\/product_tag?post=186375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}