{"id":200297,"date":"2026-05-11T15:31:52","date_gmt":"2026-05-11T14:31:52","guid":{"rendered":"https:\/\/depagterinterieurs.nl\/collectie\/uncategorized\/table-chene-cuit-u-profile-260cm\/"},"modified":"2026-05-12T11:11:14","modified_gmt":"2026-05-12T10:11:14","slug":"table-chene-cuit-u-profile-260cm","status":"publish","type":"product","link":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/tables-fr\/tables-a-manger\/table-chene-cuit-u-profile-260cm\/","title":{"rendered":"Table Ch\u00eane Cuit U-Profile 260CM"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Table \u00e0 manger avec un plateau rustique en ch\u00eane cuit et une base en m\u00e9tal noir.<\/p>\n<p>\u00c9galement disponibles en d\u2019autres tailles ou avec une autre base.<\/p>\n","protected":false},"featured_media":199721,"template":"","meta":[],"product_brand":[],"product_cat":[1072,1042,1063,1065],"product_tag":[],"class_list":{"0":"post-200297","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-de-pagter-interieurs-fr","7":"product_cat-marques","8":"product_cat-tables-fr","9":"product_cat-tables-a-manger","11":"first","12":"instock","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Table Ch\u00eane Cuit U-Profile 260CM - De Pagter Interieurs<\/title>\n<meta name=\"description\" content=\"Table \u00e0 manger avec un plateau rustique en ch\u00eane cuit et une base en m\u00e9tal noir. \u00c9galement disponible dans d\u2019autres tailles ou avec une base diff\u00e9rente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/depagterinterieurs.nl\/fr\/collectie\/tables-fr\/tables-a-manger\/table-chene-cuit-u-profile-260cm\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Table Ch\u00eane Cuit U-Profile 260CM - De Pagter Interieurs\" \/>\n<meta property=\"og:description\" content=\"Table \u00e0 manger avec un plateau rustique en ch\u00eane cuit et une base en m\u00e9tal noir. \u00c9galement disponible dans d\u2019autres tailles ou avec une base diff\u00e9rente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/depagterinterieurs.nl\/fr\/collectie\/tables-fr\/tables-a-manger\/table-chene-cuit-u-profile-260cm\/\" \/>\n<meta property=\"og:site_name\" content=\"De Pagter Interieurs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/depagterinterieurs\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T10:11:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/05\/IMG_6091.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/tables-fr\\\/tables-a-manger\\\/table-chene-cuit-u-profile-260cm\\\/\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/tables-fr\\\/tables-a-manger\\\/table-chene-cuit-u-profile-260cm\\\/\",\"name\":\"Table Ch\u00eane Cuit U-Profile 260CM - De Pagter Interieurs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/tables-fr\\\/tables-a-manger\\\/table-chene-cuit-u-profile-260cm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/tables-fr\\\/tables-a-manger\\\/table-chene-cuit-u-profile-260cm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_6091.jpg\",\"datePublished\":\"2026-05-11T14:31:52+00:00\",\"dateModified\":\"2026-05-12T10:11:14+00:00\",\"description\":\"Table \u00e0 manger avec un plateau rustique en ch\u00eane cuit et une base en m\u00e9tal noir. \u00c9galement disponible dans d\u2019autres tailles ou avec une base diff\u00e9rente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/tables-fr\\\/tables-a-manger\\\/table-chene-cuit-u-profile-260cm\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/tables-fr\\\/tables-a-manger\\\/table-chene-cuit-u-profile-260cm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/tables-fr\\\/tables-a-manger\\\/table-chene-cuit-u-profile-260cm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_6091.jpg\",\"contentUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_6091.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/tables-fr\\\/tables-a-manger\\\/table-chene-cuit-u-profile-260cm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/domicile\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collection\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collection\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Table Ch\u00eane Cuit U-Profile 260CM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/\",\"name\":\"De Pagter Interieurs\",\"description\":\"Woonwinkels in Middelburg - Domburg - Veere\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Table Ch\u00eane Cuit U-Profile 260CM - De Pagter Interieurs","description":"Table \u00e0 manger avec un plateau rustique en ch\u00eane cuit et une base en m\u00e9tal noir. \u00c9galement disponible dans d\u2019autres tailles ou avec une base diff\u00e9rente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/tables-fr\/tables-a-manger\/table-chene-cuit-u-profile-260cm\/","og_locale":"fr_FR","og_type":"article","og_title":"Table Ch\u00eane Cuit U-Profile 260CM - De Pagter Interieurs","og_description":"Table \u00e0 manger avec un plateau rustique en ch\u00eane cuit et une base en m\u00e9tal noir. \u00c9galement disponible dans d\u2019autres tailles ou avec une base diff\u00e9rente.","og_url":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/tables-fr\/tables-a-manger\/table-chene-cuit-u-profile-260cm\/","og_site_name":"De Pagter Interieurs","article_publisher":"https:\/\/www.facebook.com\/depagterinterieurs\/","article_modified_time":"2026-05-12T10:11:14+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/05\/IMG_6091.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/tables-fr\/tables-a-manger\/table-chene-cuit-u-profile-260cm\/","url":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/tables-fr\/tables-a-manger\/table-chene-cuit-u-profile-260cm\/","name":"Table Ch\u00eane Cuit U-Profile 260CM - De Pagter Interieurs","isPartOf":{"@id":"https:\/\/depagterinterieurs.nl\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/tables-fr\/tables-a-manger\/table-chene-cuit-u-profile-260cm\/#primaryimage"},"image":{"@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/tables-fr\/tables-a-manger\/table-chene-cuit-u-profile-260cm\/#primaryimage"},"thumbnailUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/05\/IMG_6091.jpg","datePublished":"2026-05-11T14:31:52+00:00","dateModified":"2026-05-12T10:11:14+00:00","description":"Table \u00e0 manger avec un plateau rustique en ch\u00eane cuit et une base en m\u00e9tal noir. \u00c9galement disponible dans d\u2019autres tailles ou avec une base diff\u00e9rente.","breadcrumb":{"@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/tables-fr\/tables-a-manger\/table-chene-cuit-u-profile-260cm\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/depagterinterieurs.nl\/fr\/collectie\/tables-fr\/tables-a-manger\/table-chene-cuit-u-profile-260cm\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/tables-fr\/tables-a-manger\/table-chene-cuit-u-profile-260cm\/#primaryimage","url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/05\/IMG_6091.jpg","contentUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/05\/IMG_6091.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/tables-fr\/tables-a-manger\/table-chene-cuit-u-profile-260cm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/depagterinterieurs.nl\/fr\/domicile\/"},{"@type":"ListItem","position":2,"name":"Collection","item":"https:\/\/depagterinterieurs.nl\/fr\/collection\/"},{"@type":"ListItem","position":3,"name":"Table Ch\u00eane Cuit U-Profile 260CM"}]},{"@type":"WebSite","@id":"https:\/\/depagterinterieurs.nl\/fr\/#website","url":"https:\/\/depagterinterieurs.nl\/fr\/","name":"De Pagter Interieurs","description":"Woonwinkels in Middelburg - Domburg - Veere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/depagterinterieurs.nl\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/product\/200297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/media\/199721"}],"wp:attachment":[{"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/media?parent=200297"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/product_brand?post=200297"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/product_cat?post=200297"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/product_tag?post=200297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}