{"id":200301,"date":"2026-05-11T15:37:08","date_gmt":"2026-05-11T14:37:08","guid":{"rendered":"https:\/\/depagterinterieurs.nl\/collectie\/uncategorized\/lampe-cruche-strado\/"},"modified":"2026-05-12T11:40:51","modified_gmt":"2026-05-12T10:40:51","slug":"lampe-cruche-strado","status":"publish","type":"product","link":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/eclairage\/lampe-cruche-strado\/","title":{"rendered":"Lampe Cruche Strado"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Lampe cruche &#8216;Strado&#8217;, compos\u00e9e d\u2019un socle en pierre et d\u2019un abat-jour en tissu.<\/p>\n","protected":false},"featured_media":199757,"template":"","meta":[],"product_brand":[],"product_cat":[1039],"product_tag":[],"class_list":{"0":"post-200301","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-eclairage","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lampe Cruche Strado - De Pagter Interieurs<\/title>\n<meta name=\"description\" content=\"Lampe cruche &#039;Strado&#039;, compos\u00e9e d\u2019un socle en pierre et d\u2019un abat-jour en tissu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/depagterinterieurs.nl\/fr\/collectie\/eclairage\/lampe-cruche-strado\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lampe Cruche Strado - De Pagter Interieurs\" \/>\n<meta property=\"og:description\" content=\"Lampe cruche &#039;Strado&#039;, compos\u00e9e d\u2019un socle en pierre et d\u2019un abat-jour en tissu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/depagterinterieurs.nl\/fr\/collectie\/eclairage\/lampe-cruche-strado\/\" \/>\n<meta property=\"og:site_name\" content=\"De Pagter Interieurs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/depagterinterieurs\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T10:40:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/05\/IMG_6101.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/eclairage\\\/lampe-cruche-strado\\\/\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/eclairage\\\/lampe-cruche-strado\\\/\",\"name\":\"Lampe Cruche Strado - De Pagter Interieurs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/eclairage\\\/lampe-cruche-strado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/eclairage\\\/lampe-cruche-strado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_6101.jpg\",\"datePublished\":\"2026-05-11T14:37:08+00:00\",\"dateModified\":\"2026-05-12T10:40:51+00:00\",\"description\":\"Lampe cruche 'Strado', compos\u00e9e d\u2019un socle en pierre et d\u2019un abat-jour en tissu.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/eclairage\\\/lampe-cruche-strado\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/eclairage\\\/lampe-cruche-strado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/eclairage\\\/lampe-cruche-strado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_6101.jpg\",\"contentUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_6101.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/eclairage\\\/lampe-cruche-strado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/domicile\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collection\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collection\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lampe Cruche Strado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/\",\"name\":\"De Pagter Interieurs\",\"description\":\"Woonwinkels in Middelburg - Domburg - Veere\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lampe Cruche Strado - De Pagter Interieurs","description":"Lampe cruche 'Strado', compos\u00e9e d\u2019un socle en pierre et d\u2019un abat-jour en tissu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/eclairage\/lampe-cruche-strado\/","og_locale":"fr_FR","og_type":"article","og_title":"Lampe Cruche Strado - De Pagter Interieurs","og_description":"Lampe cruche 'Strado', compos\u00e9e d\u2019un socle en pierre et d\u2019un abat-jour en tissu.","og_url":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/eclairage\/lampe-cruche-strado\/","og_site_name":"De Pagter Interieurs","article_publisher":"https:\/\/www.facebook.com\/depagterinterieurs\/","article_modified_time":"2026-05-12T10:40:51+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/05\/IMG_6101.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/eclairage\/lampe-cruche-strado\/","url":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/eclairage\/lampe-cruche-strado\/","name":"Lampe Cruche Strado - De Pagter Interieurs","isPartOf":{"@id":"https:\/\/depagterinterieurs.nl\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/eclairage\/lampe-cruche-strado\/#primaryimage"},"image":{"@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/eclairage\/lampe-cruche-strado\/#primaryimage"},"thumbnailUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/05\/IMG_6101.jpg","datePublished":"2026-05-11T14:37:08+00:00","dateModified":"2026-05-12T10:40:51+00:00","description":"Lampe cruche 'Strado', compos\u00e9e d\u2019un socle en pierre et d\u2019un abat-jour en tissu.","breadcrumb":{"@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/eclairage\/lampe-cruche-strado\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/depagterinterieurs.nl\/fr\/collectie\/eclairage\/lampe-cruche-strado\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/eclairage\/lampe-cruche-strado\/#primaryimage","url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/05\/IMG_6101.jpg","contentUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/05\/IMG_6101.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/eclairage\/lampe-cruche-strado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/depagterinterieurs.nl\/fr\/domicile\/"},{"@type":"ListItem","position":2,"name":"Collection","item":"https:\/\/depagterinterieurs.nl\/fr\/collection\/"},{"@type":"ListItem","position":3,"name":"Lampe Cruche Strado"}]},{"@type":"WebSite","@id":"https:\/\/depagterinterieurs.nl\/fr\/#website","url":"https:\/\/depagterinterieurs.nl\/fr\/","name":"De Pagter Interieurs","description":"Woonwinkels in Middelburg - Domburg - Veere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/depagterinterieurs.nl\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/product\/200301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/media\/199757"}],"wp:attachment":[{"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/media?parent=200301"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/product_brand?post=200301"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/product_cat?post=200301"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/product_tag?post=200301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}