{"id":217174,"date":"2026-09-01T12:23:06","date_gmt":"2026-09-01T11:23:06","guid":{"rendered":"https:\/\/depagterinterieurs.nl\/collectie\/uncategorized\/table-de-chevet-granada\/"},"modified":"2026-09-01T12:58:42","modified_gmt":"2026-09-01T11:58:42","slug":"table-de-chevet-granada","status":"publish","type":"product","link":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/petits-meubles\/tables-de-nuit\/table-de-chevet-granada\/","title":{"rendered":"Table De Chevet Granada"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Table de chevet de campagne &#8216;Granada&#8217; avec 4 tiroirs, en vieux bois de pin.<\/p>\n<p>Existe \u00e9galement en noir.<\/p>\n","protected":false},"featured_media":112546,"template":"","meta":[],"product_brand":[],"product_cat":[1072,1042,1048,1056,1059],"product_tag":[],"class_list":["post-217174","product","type-product","status-publish","has-post-thumbnail","product_cat-de-pagter-interieurs-fr","product_cat-marques","product_cat-orme-vieux-pin","product_cat-petits-meubles","product_cat-tables-de-nuit","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Table De Chevet Granada - De Pagter Interieurs<\/title>\n<meta name=\"description\" content=\"Table de chevet de campagne &#039;Granada&#039; avec 4 tiroirs, en vieux bois de pin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/depagterinterieurs.nl\/fr\/collectie\/petits-meubles\/tables-de-nuit\/table-de-chevet-granada\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Table De Chevet Granada - De Pagter Interieurs\" \/>\n<meta property=\"og:description\" content=\"Table de chevet de campagne &#039;Granada&#039; avec 4 tiroirs, en vieux bois de pin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/depagterinterieurs.nl\/fr\/collectie\/petits-meubles\/tables-de-nuit\/table-de-chevet-granada\/\" \/>\n<meta property=\"og:site_name\" content=\"De Pagter Interieurs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/depagterinterieurs\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T11:58:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2023\/04\/IMG_6622.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/petits-meubles\\\/tables-de-nuit\\\/table-de-chevet-granada\\\/\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/petits-meubles\\\/tables-de-nuit\\\/table-de-chevet-granada\\\/\",\"name\":\"Table De Chevet Granada - De Pagter Interieurs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/petits-meubles\\\/tables-de-nuit\\\/table-de-chevet-granada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/petits-meubles\\\/tables-de-nuit\\\/table-de-chevet-granada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/IMG_6622.jpeg\",\"datePublished\":\"2026-09-01T11:23:06+00:00\",\"dateModified\":\"2026-09-01T11:58:42+00:00\",\"description\":\"Table de chevet de campagne 'Granada' avec 4 tiroirs, en vieux bois de pin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/petits-meubles\\\/tables-de-nuit\\\/table-de-chevet-granada\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/petits-meubles\\\/tables-de-nuit\\\/table-de-chevet-granada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/petits-meubles\\\/tables-de-nuit\\\/table-de-chevet-granada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/IMG_6622.jpeg\",\"contentUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/IMG_6622.jpeg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collectie\\\/petits-meubles\\\/tables-de-nuit\\\/table-de-chevet-granada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/domicile\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collection\",\"item\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/collection\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Table De Chevet Granada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/\",\"name\":\"De Pagter Interieurs\",\"description\":\"Woonwinkels in Middelburg - Domburg - Veere\",\"publisher\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/#organization\",\"name\":\"De Pagter Interieurs\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/depagterinterieurs.nl\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo.svg\",\"width\":157,\"height\":53,\"caption\":\"De Pagter Interieurs\"},\"image\":{\"@id\":\"https:\\\/\\\/depagterinterieurs.nl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/depagterinterieurs\\\/\",\"https:\\\/\\\/www.instagram.com\\\/depagterinterieurs\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Table De Chevet Granada - De Pagter Interieurs","description":"Table de chevet de campagne 'Granada' avec 4 tiroirs, en vieux bois de pin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/petits-meubles\/tables-de-nuit\/table-de-chevet-granada\/","og_locale":"fr_FR","og_type":"article","og_title":"Table De Chevet Granada - De Pagter Interieurs","og_description":"Table de chevet de campagne 'Granada' avec 4 tiroirs, en vieux bois de pin.","og_url":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/petits-meubles\/tables-de-nuit\/table-de-chevet-granada\/","og_site_name":"De Pagter Interieurs","article_publisher":"https:\/\/www.facebook.com\/depagterinterieurs\/","article_modified_time":"2026-09-01T11:58:42+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2023\/04\/IMG_6622.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/petits-meubles\/tables-de-nuit\/table-de-chevet-granada\/","url":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/petits-meubles\/tables-de-nuit\/table-de-chevet-granada\/","name":"Table De Chevet Granada - De Pagter Interieurs","isPartOf":{"@id":"https:\/\/depagterinterieurs.nl\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/petits-meubles\/tables-de-nuit\/table-de-chevet-granada\/#primaryimage"},"image":{"@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/petits-meubles\/tables-de-nuit\/table-de-chevet-granada\/#primaryimage"},"thumbnailUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2023\/04\/IMG_6622.jpeg","datePublished":"2026-09-01T11:23:06+00:00","dateModified":"2026-09-01T11:58:42+00:00","description":"Table de chevet de campagne 'Granada' avec 4 tiroirs, en vieux bois de pin.","breadcrumb":{"@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/petits-meubles\/tables-de-nuit\/table-de-chevet-granada\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/depagterinterieurs.nl\/fr\/collectie\/petits-meubles\/tables-de-nuit\/table-de-chevet-granada\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/petits-meubles\/tables-de-nuit\/table-de-chevet-granada\/#primaryimage","url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2023\/04\/IMG_6622.jpeg","contentUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2023\/04\/IMG_6622.jpeg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/depagterinterieurs.nl\/fr\/collectie\/petits-meubles\/tables-de-nuit\/table-de-chevet-granada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/depagterinterieurs.nl\/fr\/domicile\/"},{"@type":"ListItem","position":2,"name":"Collection","item":"https:\/\/depagterinterieurs.nl\/fr\/collection\/"},{"@type":"ListItem","position":3,"name":"Table De Chevet Granada"}]},{"@type":"WebSite","@id":"https:\/\/depagterinterieurs.nl\/fr\/#website","url":"https:\/\/depagterinterieurs.nl\/fr\/","name":"De Pagter Interieurs","description":"Woonwinkels in Middelburg - Domburg - Veere","publisher":{"@id":"https:\/\/depagterinterieurs.nl\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/depagterinterieurs.nl\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/depagterinterieurs.nl\/fr\/#organization","name":"De Pagter Interieurs","url":"https:\/\/depagterinterieurs.nl\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/depagterinterieurs.nl\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/02\/logo.svg","contentUrl":"https:\/\/depagterinterieurs.nl\/wp-content\/uploads\/2026\/02\/logo.svg","width":157,"height":53,"caption":"De Pagter Interieurs"},"image":{"@id":"https:\/\/depagterinterieurs.nl\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/depagterinterieurs\/","https:\/\/www.instagram.com\/depagterinterieurs\/"]}]}},"_links":{"self":[{"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/product\/217174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/media\/112546"}],"wp:attachment":[{"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/media?parent=217174"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/product_brand?post=217174"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/product_cat?post=217174"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/depagterinterieurs.nl\/fr\/wp-json\/wp\/v2\/product_tag?post=217174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}